{"id":8686,"date":"2010-12-01T00:00:00","date_gmt":"2010-11-30T23:00:00","guid":{"rendered":"https:\/\/politicasdelamemoria.org\/2010\/01\/del-rio-angel-y-gordillo-giraldo-cecilio-2010-deriva-e-institucionalizacion-de-la-memoria-8\/"},"modified":"2015-06-12T12:05:28","modified_gmt":"2015-06-12T10:05:28","slug":"del-rio-angel-y-gordillo-giraldo-cecilio-2010-deriva-e-institucionalizacion-de-la-memoria-8","status":"publish","type":"post","link":"https:\/\/politicasdelamemoria.org\/en\/2010\/12\/del-rio-angel-y-gordillo-giraldo-cecilio-2010-deriva-e-institucionalizacion-de-la-memoria-8\/","title":{"rendered":"DEL R\u00cdO, A. and GORDILLO, C. (2010) Deriva e institucionalizaci\u00f3n de la memoria. Su memoria, su dignidad, su lucha: la nuestra"},"content":{"rendered":"<table style=\"width: 98%; border: #999999 0pt solid;\" border=\"0\" cellspacing=\"4\" cellpadding=\"4\">\n<tbody>\n<tr>\n<th width=\"10%\">\n<div style=\"text-align: left;\">DATE<\/div>\n<\/th>\n<th style=\"text-align: left;\" width=\"55%\">TITLE<\/th>\n<th style=\"text-align: left;\" width=\"23%\">AUTHORS<\/th>\n<th style=\"text-align: left;\" width=\"12%\">TYPE<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 15%; text-align: center;\">\n<div>\n<p>2010<\/p>\n<\/div>\n<\/td>\n<td style=\"text-align: left;\"><a href=\"https:\/\/politicasdelamemoria.org\/wp-content\/uploads\/2010\/01\/VS113_Deriva_Rio_Gordillo.pdf-1170.pdf\" target=\"_blank\">Deriva e institucionalizaci\u00f3n de la memoria. Su memoria, su dignidad, su lucha: la nuestra<\/a><\/td>\n<td style=\"width: 25%; text-align: left;\">\u00c1ngel DEL R\u00cdO<br \/>\nCecilio GORDILLO<\/td>\n<td style=\"text-align: left;\">Article<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>DATE TITLE AUTHORS TYPE 2010 Deriva e institucionalizaci\u00f3n de la memoria. Su memoria, su dignidad, su lucha: la nuestra \u00c1ngel DEL R\u00cdO Cecilio GORDILLO Article<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[607,630],"tags":[713,715,714,716],"class_list":["post-8686","post","type-post","status-publish","format-standard","hentry","category-team-publications","category-articles","tag-migracion-en","tag-migracion-en-2","tag-pdf-en","tag-pdf-en-2"],"_links":{"self":[{"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/posts\/8686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/comments?post=8686"}],"version-history":[{"count":0,"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/posts\/8686\/revisions"}],"wp:attachment":[{"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/media?parent=8686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/categories?post=8686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicasdelamemoria.org\/en\/wp-json\/wp\/v2\/tags?post=8686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}